{"id":3,"date":"2024-11-30T16:13:51","date_gmt":"2024-11-30T15:13:51","guid":{"rendered":"https:\/\/zaragoza.wordcamp.org\/2025\/welcome-to-wordcamp-zaragoza-2025\/"},"modified":"2025-01-23T16:13:21","modified_gmt":"2025-01-23T15:13:21","slug":"bienvenidos-a-wordcamp-zaragoza-2025","status":"publish","type":"post","link":"https:\/\/zaragoza.wordcamp.org\/2025\/bienvenidos-a-wordcamp-zaragoza-2025\/","title":{"rendered":"\ud83e\udd81\u00a1Bienvenidos a WordCamp Zaragoza 2025!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los d\u00edas <strong>14 y 15 de febrero de 2025<\/strong> te esperamos en <strong>ETOPIA<\/strong>, Zaragoza, para el evento de <strong>WordPress<\/strong> m\u00e1s innovador del a\u00f1o. Esta edici\u00f3n estar\u00e1 dedicada a una tem\u00e1tica apasionante y de plena actualidad: <strong>la Inteligencia Artificial<\/strong> y su impacto en desarrollo web, la creaci\u00f3n de contenidos. el dise\u00f1o&#8230;y mucho m\u00e1s.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ud83e\udd16 <strong>Explora la IA y el futuro de WordPress<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Inteligencia Artificial est\u00e1 transformando la manera en la que trabajamos, dise\u00f1amos y creamos con WordPress. Ven a <strong>descubrir y aprender<\/strong> c\u00f3mo esta tecnolog\u00eda puede ayudarte a mejorar tu flujo de trabajo, optimizar procesos y sacar m\u00e1s partido a tus proyectos.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ud83d\ude80 <strong>\u00bfPor qu\u00e9 asistir?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Porque te espera un evento lleno de aprendizaje y experiencias que te inspirar\u00e1n a explorar nuevas formas de trabajar con la IA. Aprendiendo, descubriendo y resolviendo dudas sobre su impacto en tu vida profesional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y por supuesto conectar\u00e1s con personas apasionadas por el dise\u00f1o, el desarrollo y\/o la creaci\u00f3n de contenidos.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\ud83d\udccd <strong>Nos vemos en Zaragoza<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o #WCZGZ2025 tendr\u00e1 lugar donde siempre, en <strong>ETOPIA<\/strong>, un espacio de referencia en tecnolog\u00eda e innovaci\u00f3n que nos acoge de nuevo en nuestra sexta edici\u00f3n: WordCamp Zaragoza 2025<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\uddd3 <strong>Reserva la fecha<\/strong>: <strong>14 y 15 de febrero de 2025<\/strong>.<br>\u00a1\u00danete a nosotros para explorar el futuro de WordPress de la mano de la Inteligencia Artificial! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc49 <strong>#WCZ2025<\/strong> | <strong>#WordPressAI<\/strong> | <strong>#WordCampZaragoza<\/strong><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los d\u00edas 14 y 15 de febrero de 2025 te esperamos en ETOPIA, Zaragoza, para el evento de WordPress m\u00e1s innovador del a\u00f1o. Esta edici\u00f3n estar\u00e1 dedicada a una tem\u00e1tica apasionante y de plena actualidad: la Inteligencia Artificial y su impacto en desarrollo web, la creaci\u00f3n de contenidos. el dise\u00f1o&#8230;y mucho m\u00e1s. \ud83e\udd16 Explora la [&hellip;]<\/p>\n","protected":false},"author":15788922,"featured_media":282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-3","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/zaragoza.wordcamp.org\/2025\/files\/2024\/12\/equipo-wczgz24.jpg?fit=2048%2C1365&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/posts\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/users\/15788922"}],"replies":[{"embeddable":true,"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":10,"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/posts\/3\/revisions"}],"predecessor-version":[{"id":1818,"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/posts\/3\/revisions\/1818"}],"wp:attachment":[{"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/media?parent=3"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/categories?post=3"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zaragoza.wordcamp.org\/2025\/wp-json\/wp\/v2\/tags?post=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}